{"id":6579,"date":"2015-02-24T22:51:04","date_gmt":"2015-02-24T21:51:04","guid":{"rendered":"http:\/\/www.lironjeremy.com\/lespasperdus\/?p=6579"},"modified":"2015-02-24T22:51:04","modified_gmt":"2015-02-24T21:51:04","slug":"bonnard-observations-sur-la-peinture","status":"publish","type":"post","link":"https:\/\/www.lironjeremy.com\/lespasperdus\/bonnard-observations-sur-la-peinture\/","title":{"rendered":"Bonnard, observations sur la peinture"},"content":{"rendered":"<p>Bonnard est un de ces in\u00e9puisables, un de ceux qui \u00e9chappent aux cat\u00e9gories, une sorte de figure errante. Il se tient dans cet espace d\u2019\u00e9lection entre l\u2019artiste professionnel et l\u2019amateur, entre le m\u00e9tier et l\u2019amour. <!--more--><\/p>\n<p>Il ne faut pas attendre du peintre un essai sur son art, il ne laissera au fil d\u2019une pens\u00e9e en acte pas plus que des indications, des courtes notes, des mots \u00e0 peine, comme une ponctuation. Plus que Matisse encore qui en avait dict\u00e9 le principe, Bonnard se vouant \u00e0 la peinture, s\u2019est \u00ab coup\u00e9 la langue \u00bb, ne produisant aucune th\u00e9orie, aucun commentaire sur ce qu\u2019il faisait, \u00e0 peine des constats d\u2019exp\u00e9riences. Ce qu\u2019il confie \u00e0 ses carnets, entre les notations m\u00e9t\u00e9orologiques et les croquis de circonstance, les petites \u00e9tudes quotidiennes laissant apercevoir les tableaux \u00e0 venir, para\u00eet d\u2019abord anodin, anecdotique, \u00e9nigmatique parfois par les ellipses que dessine le travail lui-m\u00eame. Les mots sont \u00e0 raz l\u2019exp\u00e9rience, sans volont\u00e9 litt\u00e9raire, effet de style. Simples, dans le seul souci du vrai : des observations. La s\u00e9lection des notes court de 1927 \u00e0 1946 et on s\u2019\u00e9tonne, se d\u00e9sesp\u00e8re un peu pour soi, d\u2019y retrouver \u00e0 plus de cinquante ans de distance ses propres pr\u00e9occupations, comme si rien du probl\u00e8me n\u2019avait \u00e9t\u00e9 r\u00e9gl\u00e9 ni m\u00eame avanc\u00e9 d\u2019un pas : on prend chacun en charge au pr\u00e9sent cette histoire qui nous d\u00e9passe. Nul progr\u00e8s, on le sait. Le domaine comme un temps \u00e9tal. \u00ab Le principal sujet, c\u2019est la surface qui a sa couleur, ses lois, par-dessus les objets \u00bb. On ne pourrait que d\u00e9velopper, la v\u00e9rit\u00e9 est l\u00e0, dans sa platitude extr\u00eame si l\u2019on peut dire, et son vertige in\u00e9puisable. Dans leur bri\u00e8vet\u00e9, leur discontinuit\u00e9, les remarques de Bonnard ont quelque chose d\u2019une pens\u00e9e orientale. Et aussi simple que cela paraisse, quelque chose semble se dire l\u00e0 de plus profond que ne le fait la phrase tordue de Maurice Denis rappelant qu\u2019un \u00ab tableau, avant toute anecdote etc. \u00bb.<br \/>\nLe \u00ab il faut savoir abandonner le tableau que l\u2019on projette \u00e0 la faveur de celui qui se fait \u00bb dont on ne sait vraiment de qui est la remarque tant il nous semble l\u2019avoir lu formul\u00e9e de mani\u00e8re semblable chez plusieurs artistes est chez Bonnard lapidaire, technique : \u00ab 2 op\u00e9rations : 1. Imaginer les moyens. 2. Reconna\u00eetre et utiliser les impr\u00e9vus de la mati\u00e8re en cours d\u2019ex\u00e9cution \u00bb.  N\u2019est-ce pas l\u00e0 le principe de s\u00e9rendipit\u00e9 dont on fait pour soi une \u00e9vidence ? V\u00e9rit\u00e9 exp\u00e9rimentale sans \u00e2ge dont t\u00e9moignait d\u00e9j\u00e0 Pline dans l\u2019anecdote qu\u2019il nous laissa d\u2019Apelle ne parvenant pas \u00e0 rendre l\u2019\u00e9cume aux naseaux du cheval \u2013 il y mettait trop d\u2019art \u2013 ne trouvant issue qu\u2019involontairement et malgr\u00e9 lui, ayant jet\u00e9 de rage et de d\u00e9sespoir sur son ouvrage l\u2019\u00e9ponge sur laquelle il essuyait les couleurs de ses pinceaux. Comme dans le dessin, le travail de peintre ne se dissocie pas des observations de vie, l\u2019un illustrant l\u2019autre ou s\u2019en faisant la m\u00e9taphore. Et quand le peintre glisse entre deux remarques sur le tableau et la peinture \u00ab \u00e0 l\u2019instant o\u00f9 l\u2019on dit qu\u2019on est heureux, on ne l\u2019est plus \u00bb, il  est difficile de n\u2019y voir qu\u2019une note d\u2019humeur, une m\u00e9lancolie. Ce qui est \u00e0 l\u2019\u0153uvre dans la langue l\u2019est aussi dans la langue picturale, ses ajustements, son rapport au r\u00e9el, la conscience de ses outils, ses \u00ab petits mensonges \u00bb. L\u2019esp\u00e8ce de litanie que dessine la liste des observations rassembl\u00e9es par Bonnard dans la s\u00e9lection qu\u2019il confie \u00e0 la revue Verve \u00e0 la fin de sa vie \u00e9voque ces po\u00e8mes chinois \u00e0 l\u2019articulation libre o\u00f9 ce n\u2019est pas la grammaire qui lie les mots mais le jeu des connivences, des \u00e9chos, des r\u00e9sonances. \u00ab Voir le motif une seule fois ou mille. L\u2019abstrait est son propre d\u00e9part. L\u2019art abstrait est un compartiment de l\u2019art. Se m\u00e9fier du ton local. Comme une musique, compter quelque fois un, deux, trois etc. (\u2026)\u00bb. D\u00e9sinvolture apparente ou libert\u00e9 qui font que le peintre \u00e9chappe au discours et \u00e0 son enclosure pour t\u00e9moigner par une observation serr\u00e9e des mouvements de pens\u00e9e, du m\u00e9tier, nous invitant apr\u00e8s lui comme sur un pas japonais.<br \/>\nLe livre que publie Fran\u00e7ois-Marie Deyrolle aux \u00e9ditions de L\u2019atelier contemporain, par sa belle clart\u00e9, le soin apport\u00e9 aux reproductions, l\u2019ampleur de son propos est une p\u00e9pite dont la place \u00e9tait d\u00e9j\u00e0 r\u00e9serv\u00e9e dans nos rayonnages \u00e0 proximit\u00e9 des monographies d\u2019Antoine Terrasse et de Jean Clair, des catalogues d\u2019exposition, de sa correspondance avec Matisse, avec Vuillard. Nous voil\u00e0 combl\u00e9s. <\/p>\n<p>Pierre Bonnard, Observations sur la peinture. Pr\u00e9face d&rsquo;Alain L\u00e9v\u00eaque et introduction d&rsquo;Antoine Terrasse. Editions l&rsquo;atelier contemporain, 15\u20ac. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonnard est un de ces in\u00e9puisables, un de ceux qui \u00e9chappent aux cat\u00e9gories, une sorte de figure errante. Il se tient dans cet espace d\u2019\u00e9lection entre l\u2019artiste professionnel et l\u2019amateur, entre le m\u00e9tier et l\u2019amour.<\/p>\n","protected":false},"author":5,"featured_media":6580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-6579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts\/6579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/comments?post=6579"}],"version-history":[{"count":1,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts\/6579\/revisions"}],"predecessor-version":[{"id":6581,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts\/6579\/revisions\/6581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/media\/6580"}],"wp:attachment":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/media?parent=6579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/categories?post=6579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/tags?post=6579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}