{"id":8119,"date":"2024-11-21T14:03:49","date_gmt":"2024-11-21T13:03:49","guid":{"rendered":"https:\/\/www.lironjeremy.com\/lespasperdus\/?p=8119"},"modified":"2024-11-21T14:03:49","modified_gmt":"2024-11-21T13:03:49","slug":"le-paysage-en-peinture","status":"publish","type":"post","link":"https:\/\/www.lironjeremy.com\/lespasperdus\/le-paysage-en-peinture\/","title":{"rendered":"Le paysage en peinture"},"content":{"rendered":"<p><em>\u00ab Toute \u0153uvre est \u00e0 la fois image, repr\u00e9sentation, et pr\u00e9sence d\u2019une existence.  \u00bb<\/em><br \/>\nGa\u00ebtan Picon<\/p>\n<p>Lorsque l\u2019on parle de peinture de paysage, ou d\u2019un tableau repr\u00e9sentant un paysage, il faut bien entendre que ce que l\u2019on d\u00e9signe comme un motif \u2013 le paysage \u2013 est engag\u00e9 simultan\u00e9ment dans un autre objet, pour ne pas dire un autre objectif d\u00e9j\u00e0 duel : la peinture, le tableau. Autant dire qu\u2019un artiste qui a d\u00e9cid\u00e9 de prendre pour vecteur d\u2019expression ou cadre d\u2019\u00e9nonciation l\u2019objet tableau engage d\u2019abord son \u00e9nergie et ses d\u00e9sirs en vue de r\u00e9aliser un tableau. Naturellement il ne s\u2019agit pas de cet objet manufactur\u00e9 que quelques comp\u00e9tences artisanales permettent de construire et qu\u2019on bricolait \u00e9tudiant avant de les acheter tout faits, mais d\u2019une sorte d\u2019objet id\u00e9el, une sorte d\u2019unit\u00e9 expressive localis\u00e9e, alchimique. Un tableau qui \u00ab tienne \u00bb, dit-on parfois. Non pas une somme de gestes, de t\u00e2ches, de signes, mais leur mise en relation singuli\u00e8re qui en fasse un nouage et un \u00e9v\u00e9nement qui r\u00e9siste aux attaques critiques que l\u2019artiste lui-m\u00eame multiplie tout au long du travail. Et j\u2019avais tent\u00e9 un parall\u00e8le il y a maintenant plus de quinze ans avec l\u2019immeuble ou le livre : cette \u00e9vidence objective fich\u00e9e sur l\u2019\u00e9tendue. Bien s\u00fbr le m\u00e9lange de choix, de d\u00e9cisions et les sinuosit\u00e9s de l\u2019intuition qui mod\u00e8lent l\u2019\u0153uvre sont difficiles \u00e0 d\u00e9crire. On ne saurait pas dire la somme d\u2019interf\u00e9rences \u00e0 l\u2019\u0153uvre, la somme de savoirs qui sont pour partie le m\u00e9tier acquis, pour partie l\u2019exp\u00e9rience plus g\u00e9n\u00e9rale des choses, la sensibilit\u00e9 et quelques vis\u00e9es obscures. Mais on peut simplifier le mouvement en r\u00e9sumant ainsi : il arrive \u00e0 un moment que la chose vous \u00e9chappe et s\u2019\u00e9loigne. C\u2019est \u00e0 ce moment pr\u00e9cis qu\u2019advient le tableau. Dans vos mains c\u2019\u00e9tait encore quelque chose d\u2019une cuisine, mais \u00e0 l\u2019instant de ce recul, le tableau vous appara\u00eet, ayant largu\u00e9 ses amarres, avec sa figure pareille \u00e0 ces visages qu\u2019on croise dans une foule et s\u2019accrochent un instant dans la conscience. Il vous semble, qu\u2019il soit \u00e9trange ou bancal, qu\u2019il correspond ou pas \u00e0 ce que vous projetiez, que depuis son lieu, il vous r\u00e9pond d\u2019un regard, tout \u00e9tonn\u00e9 lui-m\u00eame ou fi\u00e8rement. C\u2019est le r\u00e9sultat d\u2019un frayage, comme une clairi\u00e8re qui s\u2019ouvre apr\u00e8s avoir travers\u00e9 la jungle laborieuse du travail et du doute.<br \/>\nDe m\u00eame doit-on s\u2019arr\u00eater au terme de peinture vis \u00e0 vis duquel s\u2019est engag\u00e9 un mouvement semblable. Car en choisissant ce m\u00e9dium vous avez us\u00e9 du tableau, l\u00e0 encore comme objet et comme champ, avec l\u2019id\u00e9e de faire vivre la peinture, de lui donner du champ un peu comme on dit, pistolet au poing, que l\u2019on va \u00ab faire parler la poudre \u00bb. Il sera affaire de peinture. Oui, cet \u00e9trange et familier monde des mati\u00e8res et des couleurs, toutes les tonalit\u00e9s, toutes les textures, opacit\u00e9 et transparence, toutes les applications, les touches et gestes sont le lieu d\u2019une aventure tant\u00f4t intellectuelle, tant\u00f4t sensuelle, plus g\u00e9n\u00e9ralement les deux m\u00eal\u00e9es, d\u2019une exp\u00e9rience. Et l\u00e0 aussi il s\u2019agit de faire advenir un monde. Qu\u2019il soit excitant et savoureux, ludique \u00e0 la fa\u00e7on des labyrinthes. C\u2019est un lieu tr\u00e8s physique ce monde de la p\u00e2te, des recouvrements, des mixions, des transparences, du pigment, qui vous saisit comme le fait la musique, la cuisine. On y travaille en pensant avec le ventre.<br \/>\nEnsuite vient ce mot de paysage auquel on croyait tout pouvoir assujettir. Et on conviendra que s\u2019il \u00e9tait seul, s\u2019il ne s\u2019agissait que de repr\u00e9senter un paysage \u00ab bien fait \u00bb ou \u00ab ressemblant \u00bb, reconnaissable comme tel et m\u00eame harmonieux, l\u2019enjeu et l\u2019engagement ne seraient pas si grands. Les difficult\u00e9s non plus. Pierre Buraglio l\u2019a montr\u00e9 : ramassez un simple morceau de planche dont la moiti\u00e9 de la surface est badigeonn\u00e9e de bleu, de vert, de gris ou de quelque autre couleur ; basculez-l\u00e0 de mani\u00e8re \u00e0 ce que la d\u00e9marcation soit horizontale : un paysage se fait mentalement. La s\u00e9paration du ciel et de la terre, du ciel et de la mer. Ainsi d\u2019un dessin minimal d\u2019Oswald Tschirtner compos\u00e9 de deux lignes horizontales trembl\u00e9es : le plus simple des paysages ; \u00e0 peine une repr\u00e9sentation.<br \/>\nAlors il faut croiser les exigences de la peinture, du tableau et du paysage pour dire que si l\u2019objet est de r\u00e9aliser cette forme d\u2019image, d\u2019\u00e9v\u00e9nement que l\u2019on nomme tableau cela se fera \u00e0 travers le motif du paysage. Que s\u2019il sera question d\u2019une mani\u00e8re ou d\u2019une autre de paysage (il faudrait dire ce que l\u2019on entend par l\u00e0, toutes les typologies, toutes les manifestations possibles du paysage) ce sera avec l\u2019id\u00e9e qu\u2019il servira la r\u00e9alisation du tableau. Et enfin que se manifesteront \u00e0 cette occasion, ce que l\u2019on nomme \u00ab des questions de peinture \u00bb.<br \/>\nIl y a, en for\u00e7ant le trait, quelque chose d\u2019arbitraire dans mon attachement au paysage comme sujet. Et il m\u2019arrive de regarder avec envie ceux qui savent, \u00e0 l\u2019exemple de Per Kirkeby, le faire glisser aux confins du lisible ou ceux encore, comme Sean Scully, Helen Frankenthaler, Bustamante et tant d\u2019autres, qui s\u2019en passent tout \u00e0 fait et peut-\u00eatre y font parfois penser comme nous y font penser Buraglio et Tschirtner.<br \/>\nQuelquefois, c\u2019est le sentiment d\u2019\u00e9tendue ou de panorama qui caract\u00e9rise certains paysages qui m\u2019emm\u00e8ne \u00e0 le solliciter pour r\u00e9aliser ce tableau, cette peinture que j\u2019analysais pr\u00e9c\u00e9demment. Ainsi peut-\u00eatre du calligraphe qui trace au pinceau et \u00e0 l\u2019encre son po\u00e8me en immergeant son corps dans l\u2019id\u00e9e, dans la sensation int\u00e9rioris\u00e9e du paysage. Ainsi des \u0153uvres de Fabienne Verdier ou Iroko Nakajima. Je travaille, fouillant dans sa mati\u00e8re ce qui pourrait servir mon projet. Quelquefois, jouant avec, j\u2019opte pour un plan serr\u00e9 si rapproch\u00e9, je me focalise sur un d\u00e9tail, un jeu de rapports si abstraits de l\u2019id\u00e9e canonique de paysage, que celui-ci semble alors d\u00e9tourn\u00e9 pour s\u2019apparenter \u00e0 quelque chose d\u2019hybride entre nature-morte et portrait. On parlerait alors de portraits d\u2019arbres ou de plantes, du portrait d\u2019un immeuble ou d\u2019un muret. Et peut-\u00eatre d\u2019une sorte de sc\u00e8ne de genre dans la mise en relation du v\u00e9g\u00e9tal et du b\u00e2ti, c\u2019est-\u00e0-dire de gestes lyriques et de formes g\u00e9om\u00e9triques. Dans une certaine perspective, le tableau est un groupement de figures, arbre, plante, architecture, muret et m\u00eame taches ou formes abstraites autonomes. Des figures comme elles adviennent dans la peinture de Chirico ou de Tangy, dans les natures mortes de Morandi ; c\u2019est-\u00e0-dire des \u00e9v\u00e9nements entretenant une conversation libre et pourtant exacte.<br \/>\nOn peut \u00e0 cette occasion noter que, malicieusement, je n\u2019ai quasiment jamais recours au format que l\u2019on dit \u00ab paysage \u00bb horizontal. Longtemps je n\u2019ai peint que des toiles carr\u00e9es avant de trouver un terrain de jeu id\u00e9al dans toutes les variations du format dit \u00ab figure \u00bb traditionnellement d\u00e9di\u00e9 au portrait. Ces divers choix sont une mani\u00e8re, d\u2019abord inconsciente je crois, de malmener ou de jouer de la plasticit\u00e9 de cette \u00ab peinture de paysage \u00bb que l\u2019on entend quand on pense \u00e0 Poussin ou \u00e0 Rousseau. L\u2019emmener ailleurs, comme l\u2019a fait Kirkeby dans son abstraction stratigraphique ou g\u00e9omorphique. Mais cela se fait aussi dans la r\u00e9f\u00e9rence \u00e0 cet arch\u00e9type et \u00e0 l\u2019histoire occidentale du paysage en peinture. Paysage qui est indiqu\u00e9 par les variations que je travaille autour des espaces ext\u00e9rieurs et dans l\u2019\u00e9vacuation d\u00e9j\u00e0 \u00e9voqu\u00e9e de la figure et de la narration au profit d\u2019une sensation d\u2019espace, d\u2019impressions, d\u2019\u00e9tendues et de la distribution de volumes et de formes, de motifs v\u00e9g\u00e9taux et architectur\u00e9s. On retiendra pour d\u00e9signer cette s\u00e9rie embl\u00e9matique de mon travail ce terme de paysage ou quelquefois de paysage urbain ou d\u2019architectures pour s\u2019y retrouver \u00e0 gros traits.<br \/>\nRevient constamment le motif de la fen\u00eatre, de la vue, et plus g\u00e9n\u00e9ralement de la trame dans laquelle est pris le paysage. \u00c9cho \u00e0 la fa\u00e7on dont il s\u2019est immisc\u00e9 d\u2019abord dans la peinture europ\u00e9enne comme un d\u00e9tail secondaire, un arri\u00e8re-plan cadr\u00e9 par une fen\u00eatre, une ouverture, un muret au second plan d\u2019une sc\u00e8ne tenue par des figures. Il a \u00e0 voir avec le d\u00e9cor, l\u2019alentour, l\u2019environnement, le fond. Ainsi le spectateur en est le seul protagoniste, se tenant face \u00e0 lui comme face \u00e0 un panorama ou devant une fen\u00eatre. Mais le paysage est aussi un pays, un terroir, une distribution de signes. Et encore un jeu de rapports spatialis\u00e9s. Et le pr\u00e9texte \u00e0 juxtaposer des dynamiques gestuelles, des textures, des formes et des couleurs \u00e0 la mani\u00e8re d\u2019un certain paysagisme abstrait, d\u2019un paysage mental ou du paysage de sensations. A certains \u00e9gards, le motif, la grammaire du paysage est une architecture que j\u2019utilise pour \u00e9chafauder un tableau, parcourir, \u00e9laborer un monde pictural dans lesquels les sensations, les impressions, les souvenirs d\u00e9ploieront leurs charmes. Et si chaque motif suscite une mani\u00e8re de peindre, un traitement, des gestes, le paysage devient le synonyme de la peinture dans sa pr\u00e9occupation si je puis dire purement picturale (et non seulement son emploi mim\u00e9tique). Les deux se m\u00ealent de mani\u00e8re intriqu\u00e9e pour former, forger ce que Deleuze appellera souvent \u00ab le fait pictural \u00bb et qu\u2019il caract\u00e9rise comme un jeu de forces. Le paysage, dans ses dimensions g\u00e9ologiques n\u2019est-il pas la mat\u00e9rialisation immobile et mobile de ce jeu de forces ? On pense alors \u00e0 sa d\u00e9finition orientale et au terme chinois de chan-shui accolant la montagne et l\u2019eau en m\u00eame temps que l\u2019immobile et le mobile, l\u2019opaque et le translucide, le silencieux et le bruissant, le massif et le fluide\u2026 Tout un jeu de forces et de rapports stabilis\u00e9s en quelque sorte par cette notion englobante de paysage qui ressemble alors \u00e0 une \u00e9quation. \u00c9quation qui rappelle celle du tableau lui-m\u00eame dans la d\u00e9finition que j\u2019avais qualifi\u00e9e d\u2019id\u00e9elle que j\u2019en faisais.<br \/>\nOn peut imaginer comme il peut \u00eatre excitant de manipuler ces notions, ces dispositifs, ces mat\u00e9riaux pour mettre en tension la vue ou la \u00ab vedute \u00bb occidentale, trame et d\u00e9coupe auquel le tableau cette fois dans ses caract\u00e9ristiques formelles semble r\u00e9pondre, et l\u2019impalpable jeu sensible que pointe le paysage chinois. D\u2019y consid\u00e9rer aussi cette sorte d\u2019interm\u00e9diaire qui a \u00e0 voir au templum, \u00e0 l\u2019ouverture d\u2019un champ presque m\u00e9taphysique, un espace autre, h\u00e9t\u00e9rotopique dans l\u2019acception de Foucault, avec sa rythmique propre, lieu de la mise en sc\u00e8ne de signes comme chez Miro ou Kandinsky. C\u2019est pass\u00e9 ces d\u00e9tours, consid\u00e9rer ces diff\u00e9rentes perspectives et comment elles peuvent se combiner que l\u2019on peut alors parler de paysage en peinture non plus comme la simple r\u00e9alisation d\u2019un arch\u00e9type canonique, la culture d\u2019un genre, mais comme un nouage et un frayage, pour reprendre des mots lacaniens. Une tentative alchimique et joueuse. <\/p>\n<p>Image : Helen Frankenthaler, Riverhead.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Toute \u0153uvre est \u00e0 la fois image, repr\u00e9sentation, et pr\u00e9sence d\u2019une existence. \u00bb Ga\u00ebtan Picon Lorsque l\u2019on parle de peinture de paysage, ou d\u2019un tableau repr\u00e9sentant un paysage, il faut bien entendre que ce que l\u2019on d\u00e9signe comme un motif \u2013 le paysage \u2013 est engag\u00e9 simultan\u00e9ment dans un autre objet, pour ne pas [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts\/8119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/comments?post=8119"}],"version-history":[{"count":1,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts\/8119\/revisions"}],"predecessor-version":[{"id":8121,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/posts\/8119\/revisions\/8121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/media\/8120"}],"wp:attachment":[{"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/media?parent=8119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/categories?post=8119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lironjeremy.com\/lespasperdus\/wp-json\/wp\/v2\/tags?post=8119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}